{"id":6839,"date":"2022-01-26T10:01:18","date_gmt":"2022-01-26T09:01:18","guid":{"rendered":"https:\/\/www.ladymsardegna.com\/?post_type=product&#038;p=6839"},"modified":"2022-01-31T17:07:22","modified_gmt":"2022-01-31T16:07:22","slug":"pulsera-de-plata-para-mujer-en-coccu-kokos-sabegia","status":"publish","type":"product","link":"https:\/\/www.ladymsardegna.com\/es\/negozio\/gioielli-sardi\/su-coccu-onice\/bracciali-su-coccu-onice\/bracciale-donna-in-argento-su-coccu-kokos-sabegia\/","title":{"rendered":"Pulsera de plata para mujer Su Coccu Kokos Sabegia"},"content":{"rendered":"<p>Pulsera Colgante amuleto de la suerte con esfera de \u00f3nice \"Su Coccu\" y perla decorativa. Una espl\u00e9ndida pieza de joyer\u00eda artesanal de Cerde\u00f1a, elaborada con filigrana.<\/p>\n<p>Significado simb\u00f3lico de \"Su Coccu\": amuleto sardo de gran artesan\u00eda, realizado por un artesano y devoto sardo. Su Coccu sirve para proteger contra el mal de ojo; de hecho, la piedra absorbe las influencias negativas. Tradicionalmente, la piedra es de obsidiana u \u00f3nice y est\u00e1 montada sobre plata. Se lleva bajo la ropa, como un colgante, y es un poderoso amuleto contra el mal de ojo. Se dice que si las influencias negativas son demasiado fuertes, el coccu se rompe pero la persona permanece ilesa. Su Coccu, montado en un broche de plata finamente trabajado a mano, se entrega a los reci\u00e9n nacidos para protegerlos de la envidia y el mal de ojo. Se prende en la cuna, el cochecito o la ropa, y absorbe las energ\u00edas negativas. Tambi\u00e9n puede regalarse a una novia para protegerla a ella y a su relaci\u00f3n, o a un ser querido afectado por el mal de ojo.<\/p>","protected":false},"excerpt":{"rendered":"<p><strong>Pulsera de plata en coccu :<\/strong><\/p>\n<ul>\n<li>Fabricado en plata 925\u2030.<\/li>\n<li>Di\u00e1metro de la piedra de \u00f3nice 8-10 mm<\/li>\n<li>Bolas de \u00f3nix 6 uds.<\/li>\n<li>Tratamiento de microfusi\u00f3n de filigrana<\/li>\n<li>Cierre de mosquet\u00f3n<\/li>\n<li>Largo 19 cm<\/li>\n<\/ul>","protected":false},"featured_media":6870,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[176,77,175],"product_tag":[],"class_list":["post-6839","product","type-product","status-publish","has-post-thumbnail","product_cat-bracciali-su-coccu-onice","product_cat-gioielli-sardi","product_cat-su-coccu-onice","first","outofstock","shipping-taxable","purchasable","product-type-simple","col-xs-6 col-sm-4","col-md-3 col-lg-3","un-4-cols"],"_links":{"self":[{"href":"https:\/\/www.ladymsardegna.com\/es\/wp-json\/wp\/v2\/product\/6839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ladymsardegna.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ladymsardegna.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladymsardegna.com\/es\/wp-json\/wp\/v2\/comments?post=6839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ladymsardegna.com\/es\/wp-json\/wp\/v2\/media\/6870"}],"wp:attachment":[{"href":"https:\/\/www.ladymsardegna.com\/es\/wp-json\/wp\/v2\/media?parent=6839"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ladymsardegna.com\/es\/wp-json\/wp\/v2\/product_cat?post=6839"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ladymsardegna.com\/es\/wp-json\/wp\/v2\/product_tag?post=6839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}