{"id":12156,"date":"2022-04-08T11:04:11","date_gmt":"2022-04-08T09:04:11","guid":{"rendered":"https:\/\/www.ladymsardegna.com\/?post_type=product&#038;p=12156"},"modified":"2024-05-06T18:31:41","modified_gmt":"2024-05-06T16:31:41","slug":"occhio-di-santa-lucia-pulsera-colgantes-ovalados","status":"publish","type":"product","link":"https:\/\/www.ladymsardegna.com\/es\/negozio\/gioielli-sardi\/occhio-di-santa-lucia\/bracciali\/bracciale-occhio-di-santa-lucia-ciondoli-ovali\/","title":{"rendered":"Pulsera Colgantes Ovalados Occhio Di Santa Lucia"},"content":{"rendered":"<p><strong>OJO DE SANTA LUC\u00cdA<\/strong><\/p>\n<p>El Ojo de Santa Luc\u00eda es fruto del \"trabajo\" de una especie marina, un molusco llamado Astraea rugosa. El molusco segrega una sustancia que le permite construir su hogar, la concha, y el Ojo de Santa Luc\u00eda, o \"la puerta\" de su concha. El Ojo no es m\u00e1s que un peque\u00f1o op\u00e9rculo calc\u00e1reo que sirve al molusco para protegerse hasta su muerte, tras lo cual se desprende y es arrastrado por las corrientes. El molusco se encuentra en todo el Mediterr\u00e1neo. A este peque\u00f1o op\u00e9rculo se le atribuye una capacidad beneficiosa sobre los flujos de energ\u00eda que recorren todo nuestro cuerpo. S\u00edmbolo de sabidur\u00eda y conocimiento, es el emblema del movimiento y el desarrollo, junto con la capacidad de protegernos de las fuerzas malignas aumentando las energ\u00edas positivas. En la tradici\u00f3n popular italiana, el Occhio di Santa Lucia es uno de los amuletos m\u00e1s utilizados contra el mal de ojo. Tambi\u00e9n se cree que nos defiende contra las enfermedades oculares, de ah\u00ed su asociaci\u00f3n con Santa Luc\u00eda, protectora de los ojos.<\/p>","protected":false},"excerpt":{"rendered":"<p><strong>Pulsera de la suerte:<\/strong><\/p>\n<ul>\n<li>De plata 925%\u00b0\u00b0\u00b0.<\/li>\n<li>Pulsera de cadena con 7 ojos de santa lucia<\/li>\n<li>Longitud de la pulsera ajustable de 18 a 20 cm<\/li>\n<li>Cierre de mosquet\u00f3n<\/li>\n<\/ul>","protected":false},"featured_media":12159,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[171,77,158],"product_tag":[366],"class_list":["post-12156","product","type-product","status-publish","has-post-thumbnail","product_cat-bracciali","product_cat-gioielli-sardi","product_cat-occhio-di-santa-lucia","product_tag-occhio-santa-lucia","first","instock","shipping-taxable","purchasable","product-type-simple","col-xs-6 col-sm-4","col-md-3 col-lg-3","un-4-cols"],"_links":{"self":[{"href":"https:\/\/www.ladymsardegna.com\/es\/wp-json\/wp\/v2\/product\/12156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ladymsardegna.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ladymsardegna.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladymsardegna.com\/es\/wp-json\/wp\/v2\/comments?post=12156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ladymsardegna.com\/es\/wp-json\/wp\/v2\/media\/12159"}],"wp:attachment":[{"href":"https:\/\/www.ladymsardegna.com\/es\/wp-json\/wp\/v2\/media?parent=12156"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ladymsardegna.com\/es\/wp-json\/wp\/v2\/product_cat?post=12156"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ladymsardegna.com\/es\/wp-json\/wp\/v2\/product_tag?post=12156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}